{"id":616,"date":"2019-01-03T10:30:15","date_gmt":"2019-01-03T10:30:15","guid":{"rendered":"http:\/\/www.repuestosfuster.com\/blog\/?p=616"},"modified":"2019-01-15T07:23:49","modified_gmt":"2019-01-15T07:23:49","slug":"museos-de-agricultura-en-espana","status":"publish","type":"post","link":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/","title":{"rendered":"Museos de agricultura en Espa\u00f1a"},"content":{"rendered":"<p style=\"text-align: justify;\">Es habitual que al pensar en un museo las primeras im\u00e1genes que vengan a la cabeza sean paredes cubiertas de cuadros, esculturas diseminadas a trav\u00e9s del espacio de una galer\u00eda o vitrinas con f\u00f3siles de cuando los dinosaurios pastaban en las verdes praderas de la prehistoria. El concepto cl\u00e1sico que se tiene de estos espacios puede llevar a una percepci\u00f3n limitada de los mismos cuando la realidad es bien diferente. Un museo es un espacio destinado a la conservaci\u00f3n, estudio y divulgaci\u00f3n de patrimonio material e inmaterial; y eso engloba mucho m\u00e1s que cuadros, esculturas y f\u00f3siles. De esta manera, los <strong>museos de agricultura<\/strong> son una interesante propuesta que seguro que muchos profesionales del sector desconocen.<\/p>\n<p style=\"text-align: justify;\">Si bien es cierto que este tipo de museos son m\u00e1s comunes en otros pa\u00edses como Francia o Alemania, Espa\u00f1a cuenta con una peque\u00f1a pero s\u00f3lida red de infraestructuras dedicada a poner de manifiesto la estrecha relaci\u00f3n entre esta actividad y el territorio. Algunos de los principales <strong>museos de agricultura<\/strong> espa\u00f1oles son los siguientes.<\/p>\n<h3><strong>Aquagraria<\/strong><\/h3>\n<p style=\"text-align: justify;\">El m\u00e1s reciente de todos ellos es este museo inaugurado en 2012 en la localidad zaragozana de Ejea de los Caballeros. El discurso de Aquagraria se basa en la estrecha <strong>relaci\u00f3n entre el agua y la agricultura<\/strong> y su exposici\u00f3n consta de una completa colecci\u00f3n de maquinaria agr\u00edcola presentada en 3 niveles diferentes interrelacionados. El museo realiza tambi\u00e9n m\u00faltiples actividades para familias y grupos escolares entre las que destaca por su popularidad <em>Apadrina un tractor<\/em>.<\/p>\n<p style=\"text-align: justify;\">Este museo ya fue objeto hace varios meses de un <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"http:\/\/www.repuestosfuster.com\/blog\/aquagraria-museo-dedicado-la-agricultura\/\" target=\"_blank\" rel=\"noopener noreferrer\">art\u00edculo exclusivo<\/a><\/span> en este mismo blog.<\/p>\n<h3><strong>Museo de la Agricultura<\/strong><\/h3>\n<p style=\"text-align: justify;\">Este museo inaugurado en 1998 se encuentra ubicado en la localidad madrile\u00f1a de Torremocha de Jarama y cuenta con un espacio expositivo repartido entre los 500 metros cuadrados h\u00e1biles de su sede y varios rincones ubicados entre las calles y plazas de la localidad. La mayor parte de su colecci\u00f3n original proviene de <strong>donaciones privadas<\/strong> de los vecinos de Torremocha en el contexto de una iniciativa municipal para recuperar y mantener vivo parte de su patrimonio cultural.<\/p>\n<p style=\"text-align: justify;\">A\u00f1os despu\u00e9s de su inauguraci\u00f3n, <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"http:\/\/www.museoagricultura.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">el museo<\/a><\/span> fue sometido a una <strong>renovaci\u00f3n museogr\u00e1fica<\/strong> que lo dot\u00f3 de nuevas tecnolog\u00edas y ampli\u00f3 su colecci\u00f3n, compuesta por documentos, aperos y tractores antiguos.<\/p>\n<h3><strong>Museo del Tractor de \u00c9poca<\/strong><\/h3>\n<p style=\"text-align: justify;\">Castellbisbal, cerca de Barcelona, cuenta desde 2010 con un interesante espacio de 2 000 metros cuadrados donde se exponen toda clase de tractores y motores antiguos, as\u00ed como un avi\u00f3n militar americano de la d\u00e9cada de los cincuenta del pasado siglo XX. <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"http:\/\/museudeltractordepoca.com\/es\/el-museo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Este museo<\/a><\/span> cuenta con m\u00e1s de cien tractores entre los que destacan primeros modelos de marcas comerciales como <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/www.repuestosfuster.com\/es\/productos\/john-deere\" target=\"_blank\" rel=\"noopener noreferrer\">John Deere<\/a><\/span>, <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/www.repuestosfuster.com\/es\/productos\/case-ih\" target=\"_blank\" rel=\"noopener noreferrer\">Case<\/a><\/span>, <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/www.repuestosfuster.com\/es\/productos\/renault-claas\">Renault<\/a><\/span>, <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/www.repuestosfuster.com\/es\/productos\/ford\" target=\"_blank\" rel=\"noopener noreferrer\">Ford<\/a> <\/span>o <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/www.repuestosfuster.com\/es\/productos\/ebro-kubota\" target=\"_blank\" rel=\"noopener noreferrer\">Ebro<\/a><\/span>. Adem\u00e1s dispone de una cincuentena de motores estacionarios que, al igual que todos sus tractores, se encuentran en <strong>perfecto estado de funcionamiento<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Las arrancadas de tractores son uno de los principales atractivos de este museo que tambi\u00e9n organiza visitas y salidas a diversas localidades.<\/p>\n<h3><strong>Museo nacional de Ciencia y Tecnolog\u00eda<\/strong><\/h3>\n<p style=\"text-align: justify;\">Este museo depende del Ministerio de Ciencia, Innovaci\u00f3n y Universidades y est\u00e1 gestionado por la Fundaci\u00f3n Espa\u00f1ola para la Ciencia y la Tecnolog\u00eda. Aunque no se trate estrictamente de un museo de agricultura, este equipamiento p\u00fablico contiene una interesante colecci\u00f3n dedicada a la <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"http:\/\/www.muncyt.es\/portal\/site\/MUNCYT\/menuitem.e677b117332f863a24b3171001432ea0\/?vgnextoid=80d6248cf1c5a210VgnVCM1000001034e20aRCRD\" target=\"_blank\" rel=\"noopener noreferrer\">agricultura y la pesca<\/a><\/span>. En ella pueden verse maquetas, aperos y tractores datados entre mediados finales del siglo XIX y mediados del XX. Una de las piezas m\u00e1s interesantes que contiene es una <strong>locom\u00f3vil<\/strong> proveniente de la azucarera de San Isidro, aunque tambi\u00e9n pueden contemplarse sembradoras, tractores o maquinas aventadoras.<\/p>\n<p style=\"text-align: justify;\">Tanto estos cuatro museos de agricultura como el resto que hay repartidos por todo el territorio nacional llevan a cabo una importante labor de divulgaci\u00f3n de la realidad actual e hist\u00f3rica del sector. Su papel resulta de suma importancia para al acercar hasta el p\u00fablico general la relaci\u00f3n existente entre la sociedad y la actividad agr\u00edcola en cualquier lugar donde esta se desarrolle.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;616&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5\\\/5 - (1 voto)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Museos de agricultura en Espa\u00f1a&quot;,&quot;width&quot;:&quot;142.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 142.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            5\/5 - (1 voto)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>En Espa\u00f1a existen actualmente varios museos de agricultura que componen una peque\u00f1a pero s\u00f3lida red de infraestructuras relacionadas con el sector. <\/p>\n<a href=\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/\" class=\"read-more-link\">Continua leyendo <span class=\"screen-reader-text\">\"Museos de agricultura en Espa\u00f1a\"<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a>","protected":false},"author":1,"featured_media":617,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[36],"tags":[],"class_list":["post-616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-sector","penguin-post","penguin-post-not-sticky"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Museos de agricultura en Espa\u00f1a - BLOG<\/title>\n<meta name=\"description\" content=\"En Espa\u00f1a existen actualmente varios museos de agricultura que componen una peque\u00f1a pero s\u00f3lida red de infraestructuras relacionadas con el sector.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Museos de agricultura en Espa\u00f1a - BLOG\" \/>\n<meta property=\"og:description\" content=\"En Espa\u00f1a existen actualmente varios museos de agricultura que componen una peque\u00f1a pero s\u00f3lida red de infraestructuras relacionadas con el sector.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-03T10:30:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-15T07:23:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/12\/359210001Aquagraria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2362\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FUSTER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FUSTER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/\"},\"author\":{\"name\":\"FUSTER\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\"},\"headline\":\"Museos de agricultura en Espa\u00f1a\",\"datePublished\":\"2019-01-03T10:30:15+00:00\",\"dateModified\":\"2019-01-15T07:23:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/\"},\"wordCount\":705,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/12\/359210001Aquagraria.jpg\",\"articleSection\":[\"El sector\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/\",\"name\":\"Museos de agricultura en Espa\u00f1a - BLOG\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/12\/359210001Aquagraria.jpg\",\"datePublished\":\"2019-01-03T10:30:15+00:00\",\"dateModified\":\"2019-01-15T07:23:49+00:00\",\"description\":\"En Espa\u00f1a existen actualmente varios museos de agricultura que componen una peque\u00f1a pero s\u00f3lida red de infraestructuras relacionadas con el sector.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#primaryimage\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/12\/359210001Aquagraria.jpg\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/12\/359210001Aquagraria.jpg\",\"width\":2362,\"height\":565,\"caption\":\"Museos de agricultura\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.repuestosfuster.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museos de agricultura en Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"name\":\"Repuestos Fuster Blog\",\"description\":\"Tu blog de agricultura y tractores\",\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\",\"name\":\"Repuestos Fuster\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"width\":300,\"height\":120,\"caption\":\"Repuestos Fuster\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\",\"name\":\"FUSTER\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"caption\":\"FUSTER\"},\"description\":\"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.\",\"sameAs\":[\"http:\/\/www.repuestosfuster.com\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Museos de agricultura en Espa\u00f1a - BLOG","description":"En Espa\u00f1a existen actualmente varios museos de agricultura que componen una peque\u00f1a pero s\u00f3lida red de infraestructuras relacionadas con el sector.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/","og_locale":"es_ES","og_type":"article","og_title":"Museos de agricultura en Espa\u00f1a - BLOG","og_description":"En Espa\u00f1a existen actualmente varios museos de agricultura que componen una peque\u00f1a pero s\u00f3lida red de infraestructuras relacionadas con el sector.","og_url":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/","og_site_name":"BLOG","article_published_time":"2019-01-03T10:30:15+00:00","article_modified_time":"2019-01-15T07:23:49+00:00","og_image":[{"width":2362,"height":565,"url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/12\/359210001Aquagraria.jpg","type":"image\/jpeg"}],"author":"FUSTER","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"FUSTER","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#article","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/"},"author":{"name":"FUSTER","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3"},"headline":"Museos de agricultura en Espa\u00f1a","datePublished":"2019-01-03T10:30:15+00:00","dateModified":"2019-01-15T07:23:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/"},"wordCount":705,"commentCount":1,"publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/12\/359210001Aquagraria.jpg","articleSection":["El sector"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/","url":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/","name":"Museos de agricultura en Espa\u00f1a - BLOG","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#primaryimage"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/12\/359210001Aquagraria.jpg","datePublished":"2019-01-03T10:30:15+00:00","dateModified":"2019-01-15T07:23:49+00:00","description":"En Espa\u00f1a existen actualmente varios museos de agricultura que componen una peque\u00f1a pero s\u00f3lida red de infraestructuras relacionadas con el sector.","breadcrumb":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#primaryimage","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/12\/359210001Aquagraria.jpg","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/12\/359210001Aquagraria.jpg","width":2362,"height":565,"caption":"Museos de agricultura"},{"@type":"BreadcrumbList","@id":"https:\/\/www.repuestosfuster.com\/blog\/museos-de-agricultura-en-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repuestosfuster.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Museos de agricultura en Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/www.repuestosfuster.com\/blog\/#website","url":"https:\/\/www.repuestosfuster.com\/blog\/","name":"Repuestos Fuster Blog","description":"Tu blog de agricultura y tractores","publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization","name":"Repuestos Fuster","url":"https:\/\/www.repuestosfuster.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","width":300,"height":120,"caption":"Repuestos Fuster"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3","name":"FUSTER","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","caption":"FUSTER"},"description":"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.","sameAs":["http:\/\/www.repuestosfuster.com\/"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/12\/359210001Aquagraria.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8NulZ-9W","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/comments?post=616"}],"version-history":[{"count":0,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media\/617"}],"wp:attachment":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media?parent=616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/categories?post=616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/tags?post=616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}