{"id":493,"date":"2018-09-21T05:34:54","date_gmt":"2018-09-21T05:34:54","guid":{"rendered":"http:\/\/www.repuestosfuster.com\/blog\/?p=493"},"modified":"2018-09-21T05:34:54","modified_gmt":"2018-09-21T05:34:54","slug":"tractor-a-metano-mas-que-prototipo","status":"publish","type":"post","link":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/","title":{"rendered":"El tractor a metano, m\u00e1s que un prototipo"},"content":{"rendered":"<p style=\"text-align: justify;\">La aplicaci\u00f3n de las nuevas tecnolog\u00edas y el uso de energ\u00edas renovables en agricultura est\u00e1n cada vez m\u00e1s a la orden del d\u00eda. Los \u00faltimos a\u00f1os han sido especialmente prol\u00edficos en nuevas modalidades de producci\u00f3n y en sistemas que, mediante el uso de energ\u00edas limpias, buscaban obtener una mayor eficiencia y sostenibilidad en la productividad agr\u00edcola. Si hace un par de a\u00f1os la marca <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/www.repuestosfuster.com\/es\/productos\/case-ih\" target=\"_blank\" rel=\"noopener noreferrer\">Case IH<\/a><\/span> presentaba un revolucionario modelo de <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"http:\/\/www.repuestosfuster.com\/blog\/tractor\/la-realidad-del-tractor-autonomo\/\" target=\"_blank\" rel=\"noopener noreferrer\">tractor aut\u00f3nomo<\/a><\/span>, ahora parece llegarle el turno al <strong>tractor a metano<\/strong>.<\/p>\n<div class='tm-tweet-clear'><\/div>\n<div class='tm-click-to-tweet'>\n<div class='tm-ctt-text'><a href='https:\/\/twitter.com\/share?text=El+tractor+a+metano+es+ya+una+realidad+que+supone+un+paso+m%C3%A1s+hacia+la+sostenibilidad+agr%C3%ADcola.&#038;url=https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/' target='_blank'>El tractor a metano es ya una realidad que supone un paso m\u00e1s hacia la sostenibilidad agr\u00edcola.<\/a><\/div>\n<p><a href='https:\/\/twitter.com\/share?text=El+tractor+a+metano+es+ya+una+realidad+que+supone+un+paso+m%C3%A1s+hacia+la+sostenibilidad+agr%C3%ADcola.&#038;url=https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/' target='_blank' class='tm-ctt-btn'>Click To Tweet<\/a><\/p>\n<div class='tm-ctt-tip'><\/div>\n<\/div>\n<h3><strong>El nuevo concepto de tractor a metano<\/strong><\/h3>\n<p style=\"text-align: justify;\">Esta nueva iniciativa fue presentada durante el mes de febrero en el Farm Progress Show, celebrado en Iowa, Estados Unidos. El prototipo, desarrollado por <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/www.repuestosfuster.com\/es\/productos\/new-holland\" target=\"_blank\" rel=\"noopener noreferrer\">New Holland<\/a><\/span>, responde a la idea de un tractor propulsado por metano. De esta manera, una explotaci\u00f3n agraria podr\u00eda convertirse en un todo superiormente autosuficiente al ser capaz de generar tanto alimentos como la biomasa necesaria para mover la maquinaria que trabaja las tierras.<\/p>\n<p style=\"text-align: justify;\">El nuevo tractor a metano supondr\u00eda un notable ahorro respecto a un diesel est\u00e1ndar y, adem\u00e1s, contar\u00eda con una operatividad casi id\u00e9ntica. En palabras de Carlos Lambro, presidente de New Holland Agriculture: \u201cSu revolucionario motor ofrece el mismo rendimiento y tiene la misma durabilidad que su equivalente est\u00e1ndar, pero <strong>sus costes operativos son muy inferiores<\/strong>. Combinando combustibles alternativos y tecnolog\u00eda agr\u00edcola avanzada, cierra el c\u00edrculo del proyecto Energy Independent Farm, explotaci\u00f3n energ\u00e9ticamente independiente, ya que funciona con la energ\u00eda obtenida a partir de productos de la tierra y residuos\u201d.<\/p>\n<h3><strong>Una larga carrera hacia la sostenibilidad<\/strong><\/h3>\n<p style=\"text-align: justify;\">El nacimiento de este novedoso veh\u00edculo es fruto del trabajo en proyectos sostenibles que la compa\u00f1\u00eda ha desarrollado durante las \u00faltimas d\u00e9cadas. En 2006, New Holland fue el primer fabricante del mercado en ofrecer una plena compatibilidad con biodiesel. 2009 fue el a\u00f1o en el que present\u00f3 el prototipo del primer tractor del mundo propulsado con hidr\u00f3geno, el NH<sup>2<\/sup>. Pocos a\u00f1os despu\u00e9s, en 2012, la empresa desarrolla otro prototipo que funciona a base de propano y cuya l\u00ednea de investigaci\u00f3n sigue abierta en la actualidad. Finalmente, en 2013 New Holland present\u00f3 su primer prototipo de tractor a metano, el T6 Methane Power. Este modelo fue probado exitosamente por clientes y es el punto de partida del nuevo veh\u00edculo desarrollado por la marca.<\/p>\n<p style=\"text-align: justify;\">De esta manera, este\u00a0<span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/www.youtube.com\/watch?v=ftMlRrzjXz8&amp;t=35s\" target=\"_blank\" rel=\"noopener noreferrer\">nuevo tractor<\/a><\/span>\u00a0presentado a comienzos de a\u00f1o juega con la ventaja de contar con una s\u00f3lida base de experiencia sobre la que crecer. Su motor permite un desarrollo de id\u00e9ntica potencia que el de un diesel convencional, pero ahorra hasta un 30 % m\u00e1s en costes operativos. En cuanto a las emisiones, estas se reducen en un 80 % respecto a los modelos convencionales. El silencio es otro de sus puntos fuertes, ya que el ruido que este tractor genera durante el trabajo se ha mitigado en un 50 % en comparaci\u00f3n con el que produce un motor diesel.<\/p>\n<p style=\"text-align: justify;\">Otra de las bazas de este tractor a metano es su dise\u00f1o, basado en l\u00edneas automovil\u00edsticas y con una gran presencia de nuevas tecnolog\u00edas como, por ejemplo, una pantalla interactiva en la tapicer\u00eda del techo.<\/p>\n<p style=\"text-align: justify;\">Este nuevo tractor a metano puede suponer un significativo avance en el mundo de la maquinaria agr\u00edcola y de sus <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/www.repuestosfuster.com\/es\/productos\" target=\"_blank\" rel=\"noopener noreferrer\">recambios agr\u00edcolas<\/a><\/span>. El concepto de una explotaci\u00f3n auto sostenible que sea capaz de producir la energ\u00eda que mueva los veh\u00edculos que la trabajan es sin duda una idea novedosa y atractiva de cara a alcanzar un sistema trabajo m\u00e1s limpio y eficaz.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;493&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;El tractor a metano, m\u00e1s que un prototipo&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Rate this post<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hace poco menos de un a\u00f1o se present\u00f3 un nuevo modelo de tractor a metano que podr\u00eda revolucionar el actual mercado del transporte agr\u00edcola.<\/p>\n<a href=\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/\" class=\"read-more-link\">Continua leyendo <span class=\"screen-reader-text\">\"El tractor a metano, m\u00e1s que un prototipo\"<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a>","protected":false},"author":1,"featured_media":498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[36,34],"tags":[],"class_list":["post-493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-sector","category-tractor","penguin-post","penguin-post-not-sticky"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El tractor a metano, m\u00e1s que un prototipo - BLOG<\/title>\n<meta name=\"description\" content=\"Hace poco menos de un a\u00f1o se present\u00f3 un nuevo modelo de tractor a metano que podr\u00eda revolucionar el actual mercado del transporte agr\u00edcola.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El tractor a metano, m\u00e1s que un prototipo - BLOG\" \/>\n<meta property=\"og:description\" content=\"Hace poco menos de un a\u00f1o se present\u00f3 un nuevo modelo de tractor a metano que podr\u00eda revolucionar el actual mercado del transporte agr\u00edcola.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-21T05:34:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/09\/Tractor-metano-new-holand1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FUSTER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FUSTER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/\"},\"author\":{\"name\":\"FUSTER\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\"},\"headline\":\"El tractor a metano, m\u00e1s que un prototipo\",\"datePublished\":\"2018-09-21T05:34:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/\"},\"wordCount\":646,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/09\/Tractor-metano-new-holand1.jpg\",\"articleSection\":[\"El sector\",\"El tractor\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/\",\"name\":\"El tractor a metano, m\u00e1s que un prototipo - BLOG\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/09\/Tractor-metano-new-holand1.jpg\",\"datePublished\":\"2018-09-21T05:34:54+00:00\",\"description\":\"Hace poco menos de un a\u00f1o se present\u00f3 un nuevo modelo de tractor a metano que podr\u00eda revolucionar el actual mercado del transporte agr\u00edcola.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#primaryimage\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/09\/Tractor-metano-new-holand1.jpg\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/09\/Tractor-metano-new-holand1.jpg\",\"width\":1920,\"height\":460,\"caption\":\"Tractor a metano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.repuestosfuster.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El tractor a metano, m\u00e1s que un prototipo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"name\":\"Repuestos Fuster Blog\",\"description\":\"Tu blog de agricultura y tractores\",\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\",\"name\":\"Repuestos Fuster\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"width\":300,\"height\":120,\"caption\":\"Repuestos Fuster\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\",\"name\":\"FUSTER\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"caption\":\"FUSTER\"},\"description\":\"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.\",\"sameAs\":[\"http:\/\/www.repuestosfuster.com\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El tractor a metano, m\u00e1s que un prototipo - BLOG","description":"Hace poco menos de un a\u00f1o se present\u00f3 un nuevo modelo de tractor a metano que podr\u00eda revolucionar el actual mercado del transporte agr\u00edcola.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/","og_locale":"es_ES","og_type":"article","og_title":"El tractor a metano, m\u00e1s que un prototipo - BLOG","og_description":"Hace poco menos de un a\u00f1o se present\u00f3 un nuevo modelo de tractor a metano que podr\u00eda revolucionar el actual mercado del transporte agr\u00edcola.","og_url":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/","og_site_name":"BLOG","article_published_time":"2018-09-21T05:34:54+00:00","og_image":[{"width":1920,"height":460,"url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/09\/Tractor-metano-new-holand1.jpg","type":"image\/jpeg"}],"author":"FUSTER","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"FUSTER","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#article","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/"},"author":{"name":"FUSTER","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3"},"headline":"El tractor a metano, m\u00e1s que un prototipo","datePublished":"2018-09-21T05:34:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/"},"wordCount":646,"commentCount":0,"publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/09\/Tractor-metano-new-holand1.jpg","articleSection":["El sector","El tractor"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/","url":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/","name":"El tractor a metano, m\u00e1s que un prototipo - BLOG","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#primaryimage"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/09\/Tractor-metano-new-holand1.jpg","datePublished":"2018-09-21T05:34:54+00:00","description":"Hace poco menos de un a\u00f1o se present\u00f3 un nuevo modelo de tractor a metano que podr\u00eda revolucionar el actual mercado del transporte agr\u00edcola.","breadcrumb":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#primaryimage","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/09\/Tractor-metano-new-holand1.jpg","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/09\/Tractor-metano-new-holand1.jpg","width":1920,"height":460,"caption":"Tractor a metano"},{"@type":"BreadcrumbList","@id":"https:\/\/www.repuestosfuster.com\/blog\/tractor-a-metano-mas-que-prototipo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repuestosfuster.com\/blog\/"},{"@type":"ListItem","position":2,"name":"El tractor a metano, m\u00e1s que un prototipo"}]},{"@type":"WebSite","@id":"https:\/\/www.repuestosfuster.com\/blog\/#website","url":"https:\/\/www.repuestosfuster.com\/blog\/","name":"Repuestos Fuster Blog","description":"Tu blog de agricultura y tractores","publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization","name":"Repuestos Fuster","url":"https:\/\/www.repuestosfuster.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","width":300,"height":120,"caption":"Repuestos Fuster"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3","name":"FUSTER","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","caption":"FUSTER"},"description":"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.","sameAs":["http:\/\/www.repuestosfuster.com\/"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2018\/09\/Tractor-metano-new-holand1.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8NulZ-7X","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/comments?post=493"}],"version-history":[{"count":0,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/493\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media\/498"}],"wp:attachment":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media?parent=493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/categories?post=493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/tags?post=493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}