{"id":2051,"date":"2022-03-18T12:03:25","date_gmt":"2022-03-18T12:03:25","guid":{"rendered":"https:\/\/www.repuestosfuster.com\/blog\/?p=2051"},"modified":"2022-03-18T12:03:32","modified_gmt":"2022-03-18T12:03:32","slug":"el-coste-del-combustible-agricola","status":"publish","type":"post","link":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/","title":{"rendered":"El coste del combustible agr\u00edcola"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">Desde hace unos meses estamos asistiendo a un <strong><span style=\"color:#ff9900\" class=\"has-inline-color\">aumento continuado del precio<\/span> <span style=\"color:#ff9900\" class=\"has-inline-color\">del combustible<\/span><\/strong> que afecta a m\u00faltiples \u00e1mbitos profesionales entre los que, por supuesto, se encuentran los profesionales del sector agropecuario, que cada vez ven como su trabajo se hace un poco m\u00e1s inviable.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo se fija el precio del combustible?<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify\">El precio del combustible se establece seg\u00fan una proporci\u00f3n en la que cerca del 50 % corresponde a impuestos. El resto se calcula de acuerdo a factores como el coste de extracci\u00f3n, de refinamiento y de distribuci\u00f3n.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Para calcular el precio base del litro de combustible se tiene en cuenta su cotizaci\u00f3n en los mercados internacionales. Dentro de las fronteras europeas, la referencia se tiene respecto al denominado <strong>\u201c<span style=\"color:#ff9900\" class=\"has-inline-color\">barril Brent<\/span>\u201d<\/strong>, que se establece de acuerdo a factores como el <strong><span style=\"color:#ff9900\" class=\"has-inline-color\">precio base de extracci\u00f3n<\/span><\/strong> en el pa\u00eds productor, la <span style=\"color:#ff9900\" class=\"has-inline-color\"><strong>demanda<\/strong> <\/span>de combustible a nivel mundial, las <span style=\"color:#ff9900\" class=\"has-inline-color\"><strong>reservas<\/strong> <\/span>estimadas y situaciones de orden geopol\u00edtico que puedan alterar los costes. Durante estos d\u00edas, estos <strong><span style=\"color:#ff9900\" class=\"has-inline-color\">factores de orden geopol\u00edticos<\/span><\/strong> han sido clave para la desestabilizaci\u00f3n del precio del combustible debido al conflicto b\u00e9lico entre Rusia y Ucrania (aunque, y pese a la especial incidencia del conflicto, la realidad es que el precio del combustible no ha parado de aumentar desde el primer tercio de 2021). Gracias a todo esto se fija el precio base que, como ya se ha se\u00f1alado, corresponde a aproximadamente la mitad del precio total del litro de combustible.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Los impuestos del combustible<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify\">Es ahora cuando hay que hablar de los impuestos que complementan el coste total del barril. En el caso del combustible existe una carga impositiva indirecta denominada <strong><span style=\"color:#ff9900\" class=\"has-inline-color\">Impuesto Especial de Hidrocarburos<\/span><\/strong>. Este impuesto se reparte en <strong><span style=\"color:#ff9900\" class=\"has-inline-color\">dos tramos<\/span><\/strong>, uno que se deriva al Estado y otro que es recibido por las diferentes comunidades aut\u00f3nomas del pa\u00eds. Este tipo de impuestos especiales son m\u00e1s frecuentes de lo que pueda parecer y, en Espa\u00f1a, se aplican a consumos espec\u00edficos como el vino, las bebidas fermentadas, la cerveza, el tabaco, el carb\u00f3n o la electricidad, por mencionar algunos.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-white-background-color has-white-color\"\/>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-attachment-id=\"2054\" data-permalink=\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/3507716478_1687bce365_k\/\" data-orig-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/3507716478_1687bce365_k.jpg\" data-orig-size=\"2048,1365\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Combustible\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/3507716478_1687bce365_k-300x200.jpg\" data-large-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/3507716478_1687bce365_k-1024x683.jpg\" src=\"http:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/3507716478_1687bce365_k-1024x683.jpg\" alt=\"Combustible\" class=\"wp-image-2054\" srcset=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/3507716478_1687bce365_k-1024x683.jpg 1024w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/3507716478_1687bce365_k-300x200.jpg 300w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/3507716478_1687bce365_k-768x512.jpg 768w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/3507716478_1687bce365_k-1536x1024.jpg 1536w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/3507716478_1687bce365_k.jpg 2048w\" sizes=\"auto, (max-width: 599px) calc(100vw - 50px), (max-width: 767px) calc(100vw - 70px), (max-width: 991px) 429px, (max-width: 1199px) 637px, 354px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-white-background-color has-white-color\"\/>\n\n\n\n<p class=\"has-text-align-justify\">Por \u00faltimo, a todo lo comentado anteriormente hay que sumar el <span style=\"color:#ff9900\" class=\"has-inline-color\"><strong>IVA<\/strong> <\/span>del 21 % que, en el caso del barril de combustible, se aplica tanto sobre el precio base como sobre el Impuesto Especial de Hidrocarburos.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">As\u00ed, el precio final de un litro de combustible depende de tres costes diferentes: un precio base fluctuante y dos impuestos que, en conjunto, abarcan casi la mitad del coste total.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tiempos dif\u00edciles<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify\">La actual situaci\u00f3n ha provocado <strong><span style=\"color:#ff9900\" class=\"has-inline-color\">huelgas y quejas masivas<\/span><\/strong> en sectores como el del transporte. Esto afecta al consumidor final, pero tambi\u00e9n a \u00e1mbitos como el <strong><span style=\"color:#ff9900\" class=\"has-inline-color\">agropecuario<\/span><\/strong>, que ve c\u00f3mo su coste de su trabajo aumenta y, al mismo tiempo, la distribuci\u00f3n de su producci\u00f3n se ve comprometida.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Con el aumento del precio del combustible, muchos agricultores y ganaderos se ven obligados a hacer cuentas y recalcular la rentabilidad de su trabajo en funci\u00f3n de este aumento de precios. Un tractor puede trabajar de media entre cinco y seis horas diarias a un ritmo de consumo de entre diez y catorce litros por hora, y eso teniendo en cuenta que muchas explotaciones no solo cuentan con una m\u00e1quina a motor.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La situaci\u00f3n se presenta como delicada para buena parte del sector agropecuario, que aunque ha realizado protestas (m\u00e1s discretas que las de otros sectores) debe fijar sus esperanzas en una reducci\u00f3n impositiva que ya ha sido anunciada o en intentar realizar peque\u00f1as acciones que conlleven un descenso en el nivel de <strong><a href=\"https:\/\/www.repuestosfuster.com\/blog\/ahorrar-combustible-en-el-tractor\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-luminous-vivid-orange-color\">consumo de combustible<\/span><\/a><\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-white-background-color has-white-color\"\/>\n\n\n\n<p>Imagen principal de <a href=\"https:\/\/www.flickr.com\/photos\/arg_flickr\/37764519164\/\" data-type=\"URL\" data-id=\"https:\/\/www.flickr.com\/photos\/arg_flickr\/37764519164\/\" target=\"_blank\" rel=\"noreferrer noopener\">Andrew<\/a>.<\/p>\n\n\n\n<p>Imagen central de <a href=\"https:\/\/www.flickr.com\/photos\/otubo\/3507716478\/\" data-type=\"URL\" data-id=\"https:\/\/www.flickr.com\/photos\/otubo\/3507716478\/\" target=\"_blank\" rel=\"noreferrer noopener\">Eduardo Otubo<\/a>.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;2051&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;El coste del combustible agr\u00edcola&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Rate this post<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>El aumento del precio del combustible se ha convertido en las \u00faltimas semanas en una de las principales preocupaciones de muchos sectores productivos.<\/p>\n<a href=\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/\" class=\"read-more-link\">Continua leyendo <span class=\"screen-reader-text\">\"El coste del combustible agr\u00edcola\"<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a>","protected":false},"author":1,"featured_media":2052,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[36,1],"tags":[],"class_list":["post-2051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-sector","category-noticias","penguin-post","penguin-post-not-sticky"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El coste del combustible agr\u00edcola - BLOG<\/title>\n<meta name=\"description\" content=\"El aumento del precio del combustible se ha convertido en las \u00faltimas semanas en una de las principales preocupaciones de muchos sectores productivos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El coste del combustible agr\u00edcola - BLOG\" \/>\n<meta property=\"og:description\" content=\"El aumento del precio del combustible se ha convertido en las \u00faltimas semanas en una de las principales preocupaciones de muchos sectores productivos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-18T12:03:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-18T12:03:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/37764519164_8eda818280_k-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FUSTER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FUSTER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/\"},\"author\":{\"name\":\"FUSTER\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\"},\"headline\":\"El coste del combustible agr\u00edcola\",\"datePublished\":\"2022-03-18T12:03:25+00:00\",\"dateModified\":\"2022-03-18T12:03:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/\"},\"wordCount\":627,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/37764519164_8eda818280_k-1.jpg\",\"articleSection\":[\"El sector\",\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/\",\"name\":\"El coste del combustible agr\u00edcola - BLOG\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/37764519164_8eda818280_k-1.jpg\",\"datePublished\":\"2022-03-18T12:03:25+00:00\",\"dateModified\":\"2022-03-18T12:03:32+00:00\",\"description\":\"El aumento del precio del combustible se ha convertido en las \u00faltimas semanas en una de las principales preocupaciones de muchos sectores productivos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#primaryimage\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/37764519164_8eda818280_k-1.jpg\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/37764519164_8eda818280_k-1.jpg\",\"width\":1920,\"height\":460,\"caption\":\"Combustible\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.repuestosfuster.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El coste del combustible agr\u00edcola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"name\":\"Repuestos Fuster Blog\",\"description\":\"Tu blog de agricultura y tractores\",\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\",\"name\":\"Repuestos Fuster\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"width\":300,\"height\":120,\"caption\":\"Repuestos Fuster\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\",\"name\":\"FUSTER\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"caption\":\"FUSTER\"},\"description\":\"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.\",\"sameAs\":[\"http:\/\/www.repuestosfuster.com\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El coste del combustible agr\u00edcola - BLOG","description":"El aumento del precio del combustible se ha convertido en las \u00faltimas semanas en una de las principales preocupaciones de muchos sectores productivos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/","og_locale":"es_ES","og_type":"article","og_title":"El coste del combustible agr\u00edcola - BLOG","og_description":"El aumento del precio del combustible se ha convertido en las \u00faltimas semanas en una de las principales preocupaciones de muchos sectores productivos.","og_url":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/","og_site_name":"BLOG","article_published_time":"2022-03-18T12:03:25+00:00","article_modified_time":"2022-03-18T12:03:32+00:00","og_image":[{"width":1920,"height":460,"url":"http:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/37764519164_8eda818280_k-1.jpg","type":"image\/jpeg"}],"author":"FUSTER","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"FUSTER","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#article","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/"},"author":{"name":"FUSTER","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3"},"headline":"El coste del combustible agr\u00edcola","datePublished":"2022-03-18T12:03:25+00:00","dateModified":"2022-03-18T12:03:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/"},"wordCount":627,"commentCount":0,"publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/37764519164_8eda818280_k-1.jpg","articleSection":["El sector","Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/","url":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/","name":"El coste del combustible agr\u00edcola - BLOG","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#primaryimage"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/37764519164_8eda818280_k-1.jpg","datePublished":"2022-03-18T12:03:25+00:00","dateModified":"2022-03-18T12:03:32+00:00","description":"El aumento del precio del combustible se ha convertido en las \u00faltimas semanas en una de las principales preocupaciones de muchos sectores productivos.","breadcrumb":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#primaryimage","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/37764519164_8eda818280_k-1.jpg","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/37764519164_8eda818280_k-1.jpg","width":1920,"height":460,"caption":"Combustible"},{"@type":"BreadcrumbList","@id":"https:\/\/www.repuestosfuster.com\/blog\/el-coste-del-combustible-agricola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repuestosfuster.com\/blog\/"},{"@type":"ListItem","position":2,"name":"El coste del combustible agr\u00edcola"}]},{"@type":"WebSite","@id":"https:\/\/www.repuestosfuster.com\/blog\/#website","url":"https:\/\/www.repuestosfuster.com\/blog\/","name":"Repuestos Fuster Blog","description":"Tu blog de agricultura y tractores","publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization","name":"Repuestos Fuster","url":"https:\/\/www.repuestosfuster.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","width":300,"height":120,"caption":"Repuestos Fuster"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3","name":"FUSTER","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","caption":"FUSTER"},"description":"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.","sameAs":["http:\/\/www.repuestosfuster.com\/"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2022\/03\/37764519164_8eda818280_k-1.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8NulZ-x5","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/2051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/comments?post=2051"}],"version-history":[{"count":0,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/2051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media\/2052"}],"wp:attachment":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media?parent=2051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/categories?post=2051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/tags?post=2051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}