{"id":1209,"date":"2020-02-19T08:50:22","date_gmt":"2020-02-19T08:50:22","guid":{"rendered":"http:\/\/www.repuestosfuster.com\/blog\/?p=1209"},"modified":"2020-02-19T08:53:20","modified_gmt":"2020-02-19T08:53:20","slug":"el-asiento-del-tractor-importancia","status":"publish","type":"post","link":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/","title":{"rendered":"La importancia del asiento del tractor"},"content":{"rendered":"<p style=\"text-align: justify;\">Las largas jornadas de trabajo a lomos de un veh\u00edculo agr\u00edcola pueden provocar da\u00f1os f\u00edsicos y ps\u00edquicos en el tractorista si este no adopta las medidas de seguridad m\u00ednimas necesarias. En este sentido, el <span style=\"color: #ff9900;\"><strong>asiento del tractor<\/strong><\/span> es uno de los elementos que m\u00e1s hay que tener en cuenta ya que asegura la buena postura del tractorista al mismo tiempo que se encarga de absorber una gran parte de las <strong>vibraciones<\/strong> producidas durante la conducci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La presencia de asientos ergon\u00f3micos en los tractores no solamente responde a una necesidad de comodidad en el trabajo. La <span style=\"color: #ff9900;\"><strong><a style=\"color: #ff9900;\" href=\"http:\/\/www.repuestosfuster.com\/blog\/aumentar-la-seguridad-en-tractores\/\" target=\"_blank\" rel=\"noopener noreferrer\">seguridad<\/a><\/strong><\/span> es la principal raz\u00f3n del dise\u00f1o de este elemento, pensado espec\u00edficamente para garantizar el bienestar del operario que se siente sobre \u00e9l. El asiento del tractor, por ejemplo, puede proteger al conductor en caso de <span style=\"color: #ff9900;\"><strong><a style=\"color: #ff9900;\" href=\"http:\/\/www.repuestosfuster.com\/blog\/evitar-el-vuelco-del-tractor\/\" target=\"_blank\" rel=\"noopener noreferrer\">vuelco<\/a><\/strong><\/span>, pero su principal labor ser\u00e1 reducir el impacto de las vibraciones de baja frecuencia que se desarrollan mientras el veh\u00edculo est\u00e1 en marcha y que, en condiciones de normalidad, terminan por incidir sobre la cabina y el cuerpo del operario.<\/p>\n<h3><strong>El impacto de las vibraciones<\/strong><\/h3>\n<p style=\"text-align: justify;\">Estas <span style=\"color: #ff9900;\"><strong><a style=\"color: #ff9900;\" href=\"http:\/\/www.repuestosfuster.com\/blog\/vibracion-mecanica-en-tractores\/\" target=\"_blank\" rel=\"noopener noreferrer\">vibraciones<\/a><\/strong><\/span> provocan incomodidad, pero sobre todo pueden ser la causa de dolencias y lesiones permanentes. Pueden incidir sobre el est\u00f3mago provocando problemas ulcerosos o g\u00e1stricos; pero tambi\u00e9n pueden afectar a otras partes del cuerpo como la columna vertebral abriendo paso a diferentes patolog\u00edas lumbares. As\u00ed, la necesidad de que el asiento del tractor est\u00e9 <span style=\"color: #ff9900;\"><strong>homologado<\/strong><\/span> con el sello CE y responda a unas caracter\u00edsticas b\u00e1sicas de seguridad deber\u00eda ser una de las preocupaciones b\u00e1sicas de cualquiera que acostumbre a trabajar sobre un veh\u00edculo agr\u00edcola.<\/p>\n<p><\/br><br \/>\n<div id=\"attachment_1213\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1213\" data-attachment-id=\"1213\" data-permalink=\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/7104858835_73fd5d0ee0_c\/\" data-orig-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/7104858835_73fd5d0ee0_c.jpg\" data-orig-size=\"799,533\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"asiento tractor\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/7104858835_73fd5d0ee0_c-300x200.jpg\" data-large-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/7104858835_73fd5d0ee0_c.jpg\" class=\"wp-image-1213\" src=\"http:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/7104858835_73fd5d0ee0_c.jpg\" alt=\"asiento tractor\" width=\"640\" height=\"427\" srcset=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/7104858835_73fd5d0ee0_c.jpg 799w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/7104858835_73fd5d0ee0_c-300x200.jpg 300w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/7104858835_73fd5d0ee0_c-768x512.jpg 768w\" sizes=\"auto, (max-width: 599px) calc(100vw - 50px), (max-width: 767px) calc(100vw - 70px), (max-width: 991px) 429px, (max-width: 1199px) 637px, 354px\" \/><p id=\"caption-attachment-1213\" class=\"wp-caption-text\">Asiento de tractor antiguo<\/p><\/div><\/p>\n<h3><strong>La importancia de regular el asiento del tractor<\/strong><\/h3>\n<p style=\"text-align: justify;\">Cada conductor cuenta con unas caracter\u00edsticas f\u00edsicas propias que deben ajustarse a los par\u00e1metros del asiento del tractor, por lo que la regulaci\u00f3n de este es una de las tareas fundamentales a la hora de asegurar su efectividad. Una mala posici\u00f3n tendr\u00e1 consecuencias como el aumento de la magnitud de las vibraciones, que provocar\u00e1 mayores da\u00f1os sobre el tractorista. De esta manera, la regulaci\u00f3n del asiento deber\u00e1 realizarse atendiendo a las indicaciones propias del fabricante aunque, por lo general, se recomienda que la altura del asiento se establezca hacia la mitad de su recorrido vertical.<\/p>\n<p style=\"text-align: justify;\">Existen diferentes tipos de suspensi\u00f3n. Una de las m\u00e1s eficientes es la <span style=\"color: #ff9900;\"><strong>neum\u00e1tica<\/strong><\/span>, que cuenta con una c\u00e1mara de aire con un compresor interno que es alimentado por la bater\u00eda. Los asientos que cuentan con este tipo de sistema pueden regularse mediante o un mando o autom\u00e1ticamente, ajust\u00e1ndose al peso del conductor cuando este se sienta.<\/p>\n<p style=\"text-align: justify;\">Otra clase de suspensi\u00f3n es la <span style=\"color: #ff9900;\"><strong>mec\u00e1nica<\/strong><\/span>, que acostumbra a contar con un sistema de resortes y amortiguadores bajo el sill\u00edn. Algunos asientos de suspensi\u00f3n mec\u00e1nica no permiten la regulaci\u00f3n en altura, pero la mayor\u00eda s\u00ed que incluye esta opci\u00f3n, como es el caso de los modelos de tijera o de tipo vertical.<\/p>\n<h3><strong>\u00bfCu\u00e1ndo cambiar el asiento del tractor?<\/strong><\/h3>\n<p style=\"text-align: justify;\">La vida \u00fatil del asiento del tractor suele ser larga. No obstante, y al margen de la decisi\u00f3n personal del operario, este deber\u00e1 ser renovado si se dan alguna de las siguientes situaciones.<\/p>\n<ul>\n<li>\n<p style=\"text-align: justify;\">El sistema de regulaci\u00f3n se bloquea o no funciona correctamente.<\/p>\n<\/li>\n<li>\n<p style=\"text-align: justify;\">La suspensi\u00f3n se bloquea o no funciona correctamente.<\/p>\n<\/li>\n<li>\n<p style=\"text-align: justify;\">El sistema neum\u00e1tico sufre de fugas o no se regula correctamente.<\/p>\n<\/li>\n<li>\n<p style=\"text-align: justify;\">La tapicer\u00eda est\u00e1 deteriorada.<\/p>\n<\/li>\n<li>\n<p style=\"text-align: justify;\">El conductor comienza a sufrir dolencias derivadas de la exposici\u00f3n a las vibraciones del tractor.<\/p>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">En l\u00edneas generales, el asiento del tractor es un elemento fundamental durante el trabajo agr\u00edcola cuyo cuidado debe ser tan importante como el del resto de <span style=\"color: #ff9900;\"><strong><a style=\"color: #ff9900;\" href=\"https:\/\/www.repuestosfuster.com\/es\/productos\" target=\"_blank\" rel=\"noopener noreferrer\">componentes mec\u00e1nicos<\/a><\/strong><\/span>. Este no solamente garantiza la comodidad del operario, tambi\u00e9n es un instrumento de seguridad indispensable.<\/p>\n<p><\/br><\/p>\n<p style=\"text-align: justify;\">Imagen central de <a href=\"https:\/\/www.flickr.com\/photos\/taylor90\/7104858835\/\" target=\"_blank\" rel=\"noopener noreferrer\">Taylor Bennett<\/a><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;1209&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5\\\/5 - (1 voto)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;La importancia del asiento del tractor&quot;,&quot;width&quot;:&quot;142.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 142.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            5\/5 - (1 voto)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>El asiento del tractor es un elemento fundamental del mismo. No solo asegura la comodidad del conductor, sino que tambi\u00e9n garantiza su seguridad.<\/p>\n<a href=\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/\" class=\"read-more-link\">Continua leyendo <span class=\"screen-reader-text\">\"La importancia del asiento del tractor\"<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a>","protected":false},"author":1,"featured_media":1210,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[34,35],"tags":[],"class_list":["post-1209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tractor","category-seguridad","penguin-post","penguin-post-not-sticky"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La importancia del asiento del tractor - BLOG<\/title>\n<meta name=\"description\" content=\"El asiento del tractor es un elemento fundamental del mismo. No solo asegura la comodidad del conductor, sino que tambi\u00e9n garantiza su seguridad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La importancia del asiento del tractor - BLOG\" \/>\n<meta property=\"og:description\" content=\"El asiento del tractor es un elemento fundamental del mismo. No solo asegura la comodidad del conductor, sino que tambi\u00e9n garantiza su seguridad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-19T08:50:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-19T08:53:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/asiento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FUSTER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FUSTER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/\"},\"author\":{\"name\":\"FUSTER\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\"},\"headline\":\"La importancia del asiento del tractor\",\"datePublished\":\"2020-02-19T08:50:22+00:00\",\"dateModified\":\"2020-02-19T08:53:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/\"},\"wordCount\":682,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/asiento.jpg\",\"articleSection\":[\"El tractor\",\"Seguridad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/\",\"name\":\"La importancia del asiento del tractor - BLOG\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/asiento.jpg\",\"datePublished\":\"2020-02-19T08:50:22+00:00\",\"dateModified\":\"2020-02-19T08:53:20+00:00\",\"description\":\"El asiento del tractor es un elemento fundamental del mismo. No solo asegura la comodidad del conductor, sino que tambi\u00e9n garantiza su seguridad.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#primaryimage\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/asiento.jpg\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/asiento.jpg\",\"width\":1920,\"height\":460,\"caption\":\"asiento del tractor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.repuestosfuster.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La importancia del asiento del tractor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"name\":\"Repuestos Fuster Blog\",\"description\":\"Tu blog de agricultura y tractores\",\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\",\"name\":\"Repuestos Fuster\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"width\":300,\"height\":120,\"caption\":\"Repuestos Fuster\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\",\"name\":\"FUSTER\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"caption\":\"FUSTER\"},\"description\":\"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.\",\"sameAs\":[\"http:\/\/www.repuestosfuster.com\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La importancia del asiento del tractor - BLOG","description":"El asiento del tractor es un elemento fundamental del mismo. No solo asegura la comodidad del conductor, sino que tambi\u00e9n garantiza su seguridad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/","og_locale":"es_ES","og_type":"article","og_title":"La importancia del asiento del tractor - BLOG","og_description":"El asiento del tractor es un elemento fundamental del mismo. No solo asegura la comodidad del conductor, sino que tambi\u00e9n garantiza su seguridad.","og_url":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/","og_site_name":"BLOG","article_published_time":"2020-02-19T08:50:22+00:00","article_modified_time":"2020-02-19T08:53:20+00:00","og_image":[{"width":1920,"height":460,"url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/asiento.jpg","type":"image\/jpeg"}],"author":"FUSTER","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"FUSTER","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#article","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/"},"author":{"name":"FUSTER","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3"},"headline":"La importancia del asiento del tractor","datePublished":"2020-02-19T08:50:22+00:00","dateModified":"2020-02-19T08:53:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/"},"wordCount":682,"commentCount":0,"publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/asiento.jpg","articleSection":["El tractor","Seguridad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/","url":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/","name":"La importancia del asiento del tractor - BLOG","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#primaryimage"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/asiento.jpg","datePublished":"2020-02-19T08:50:22+00:00","dateModified":"2020-02-19T08:53:20+00:00","description":"El asiento del tractor es un elemento fundamental del mismo. No solo asegura la comodidad del conductor, sino que tambi\u00e9n garantiza su seguridad.","breadcrumb":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#primaryimage","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/asiento.jpg","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/asiento.jpg","width":1920,"height":460,"caption":"asiento del tractor"},{"@type":"BreadcrumbList","@id":"https:\/\/www.repuestosfuster.com\/blog\/el-asiento-del-tractor-importancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repuestosfuster.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La importancia del asiento del tractor"}]},{"@type":"WebSite","@id":"https:\/\/www.repuestosfuster.com\/blog\/#website","url":"https:\/\/www.repuestosfuster.com\/blog\/","name":"Repuestos Fuster Blog","description":"Tu blog de agricultura y tractores","publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization","name":"Repuestos Fuster","url":"https:\/\/www.repuestosfuster.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","width":300,"height":120,"caption":"Repuestos Fuster"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3","name":"FUSTER","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","caption":"FUSTER"},"description":"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.","sameAs":["http:\/\/www.repuestosfuster.com\/"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/02\/asiento.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8NulZ-jv","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/1209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/comments?post=1209"}],"version-history":[{"count":0,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/1209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media\/1210"}],"wp:attachment":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media?parent=1209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/categories?post=1209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/tags?post=1209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}