{"id":1148,"date":"2020-01-15T13:16:39","date_gmt":"2020-01-15T13:16:39","guid":{"rendered":"http:\/\/www.repuestosfuster.com\/blog\/?p=1148"},"modified":"2020-05-15T09:15:51","modified_gmt":"2020-05-15T09:15:51","slug":"case-ih-la-historia-una-marca","status":"publish","type":"post","link":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/","title":{"rendered":"Case IH, historia de una marca"},"content":{"rendered":"<p style=\"text-align: justify;\">La reconocida marca de maquinaria agr\u00edcola <strong>Case IH<\/strong> tienes sus or\u00edgenes en dos empresas fundadas durante los \u00faltimos a\u00f1os de la primera mitad del siglo XIX. En 1842, Jerome Increase Case funda en Racine, Wisconsin, la <strong>Racine Threshing Machine Works<\/strong>. Unos a\u00f1os m\u00e1s tarde, en 1847, nace en Chicago la <strong>McCormick Harvesting Machine<\/strong>, fundada por Cyrus McCormick. Desde el principio, ambas empresas se distinguen por la calidad de sus productos y consolidan r\u00e1pidamente una buena posici\u00f3n en el mercado de la maquinaria y los <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"http:\/\/www.repuestosfuster.com\/es\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>repuestos agr\u00edcolas<\/strong><\/a><\/span>.<\/p>\n<h3>Primeros\u00a0contactos<\/h3>\n<p style=\"text-align: justify;\">En 1869, Case se convierte en la primera persona en aplicar el <strong>motor a vapor<\/strong> a un tractor, m\u00e1s concretamente a las ruedas; la principal tracci\u00f3n de este modelo sigue siendo de car\u00e1cter animal. En 1871 se produce el primer acercamiento entre ambas empresas cuando el tristemente famoso incendio de Chicago se lleva por delante la f\u00e1brica de McCormick y Case se ofrece para elaborar parte de su maquinaria. Sin embargo, McCormick rechaza la propuesta y construye una nueva f\u00e1brica al sudeste de la ciudad.<\/p>\n<p style=\"text-align: justify;\">Como fruto de una constante innovaci\u00f3n, en 1892 Case dise\u00f1a y realiza el <strong>primer tractor a gasolina<\/strong>, conocido como Tractor Paterson. Este, sin embargo, no fue bien acogido por el mercado y la empresa tuvo que esperar hasta 1911 para volver a elaborar veh\u00edculos de esta clase.<\/p>\n<p><\/br><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1152\" data-permalink=\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/case_ih_2\/\" data-orig-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH_2.jpg\" data-orig-size=\"1023,682\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;Photography by SteVan&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Case IH 2\" data-image-description=\"&lt;p&gt;Case IH 2&lt;\/p&gt;\n\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH_2-300x200.jpg\" data-large-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH_2.jpg\" class=\" wp-image-1152 aligncenter\" src=\"http:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH_2.jpg\" alt=\"Case IH 2\" width=\"630\" height=\"420\" srcset=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH_2.jpg 1023w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH_2-300x200.jpg 300w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH_2-768x512.jpg 768w\" sizes=\"auto, (max-width: 599px) calc(100vw - 50px), (max-width: 767px) calc(100vw - 70px), (max-width: 991px) 429px, (max-width: 1199px) 637px, 354px\" \/><\/p>\n<h3><strong>Nuevas compa\u00f1\u00edas, nuevos retos<\/strong><\/h3>\n<p style=\"text-align: justify;\">A comienzos del siglo XX, McCormick y otras cuatro compa\u00f1\u00edas m\u00e1s se fusionan para crear <strong>International Harvester Company<\/strong>, una nueva empresa que tiene en el enorme tractor Tita\u00e1, fabricado en 1910, uno de sus primeros y m\u00e1s sonados \u00e9xitos. Este tractor ya aunaba dos de las caracter\u00edsticas principales de los futuros veh\u00edculos de la compa\u00f1\u00eda: tama\u00f1o y fuerza. En 1919, esta nueva compa\u00f1\u00eda dise\u00f1a la primera toma de fuerza comercial y, en 1923, inaugura la serie Farmall, primera para cultivo regular y que ser\u00e1 la responsable de gran parte del \u00e9xito y la fama de la marca.<\/p>\n<p style=\"text-align: justify;\">International Harvester Company contin\u00faa creciendo conforme pasan los a\u00f1os y sus tractores de color rojo se posicionan como una referencia de primer orden en el mundo agr\u00edcola. Paralelamente a ella, Case desarrolla una carrera profesional plagada de \u00e9xitos comerciales como la serie 94, con tracci\u00f3n a las cuatro ruedas y que ser\u00e1 el entorno del que surgir\u00e1 el modelo 4994, la m\u00e1quina m\u00e1s poderosa fabricada por la compa\u00f1\u00eda.<\/p>\n<h3><strong>El nacimiento de Case IH<\/strong><\/h3>\n<p style=\"text-align: justify;\">En 1985, la historia de esta marca da un vuelco definitivo cuando es comprada por Case dando lugar a <strong>Case IH<\/strong>, que nace siendo ya la segunda productora de maquinaria agr\u00edcola del mundo. El primer veh\u00edculo creado por esta <strong><span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/www.repuestosfuster.com\/es\/productos\/case-ih\" target=\"_blank\" rel=\"noopener noreferrer\">nueva compa\u00f1\u00eda<\/a><\/span><\/strong> es el tractor Magnum, un veh\u00edculo que sumaba en su ser la capacidad ingeniera de International Harvest y de Case. Pocos a\u00f1os despu\u00e9s de iniciar su actividad, las sembradoras, retroexcavadoras y cosechadoras Case IH fueron incluidas en la lista de las mejores fabricadas en Estados Unidos.<\/p>\n<p style=\"text-align: justify;\">A finales del siglo XX, <a href=\"https:\/\/www.repuestosfuster.com\/es\/productos\/fiat\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><span style=\"color: #ff9900;\">Fiat<\/span><\/strong><\/a> adquiere Case Ih para unirla a <a href=\"https:\/\/www.repuestosfuster.com\/es\/productos\/new-holland\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><span style=\"color: #ff9900;\">New Holland<\/span><\/strong><\/a>. El resultado de este proceso es la aparici\u00f3n del grupo <a href=\"https:\/\/es.wikipedia.org\/wiki\/CNH\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><span style=\"color: #ff9900;\">CNH Global<\/span><\/strong><\/a>, que a partir de entonces se dedicar\u00e1 a la fabricaci\u00f3n de maquinaria agr\u00edcola y para construcci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Desde entonces, la marca Case IH no ha dejado de crecer y evolucionar tecnol\u00f3gica e industrialmente, asentando y afianzando definitivamente la merecida fama de una compa\u00f1\u00eda que se ha ganado su posici\u00f3n preeminente en el mercado de tractores a golpe de esfuerzo y trabajo continuado.<\/p>\n<p style=\"text-align: justify;\">Im\u00e1genes de <a href=\"https:\/\/www.flickr.com\/photos\/studio601photography\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #ff9900;\"><strong>StevanBaird<\/strong><\/span><\/a><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;1148&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5\\\/5 - (1 voto)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Case IH, historia de una marca&quot;,&quot;width&quot;:&quot;142.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 142.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            5\/5 - (1 voto)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>La historia de la marca Case Ih comienza en el a\u00f1o 1985 tras muchos a\u00f1os de trabajo y \u00e9xito por parte de diferentes compa\u00f1\u00edas de maquinaria agr\u00edcola.<\/p>\n<a href=\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/\" class=\"read-more-link\">Continua leyendo <span class=\"screen-reader-text\">\"Case IH, historia de una marca\"<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a>","protected":false},"author":1,"featured_media":1150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[34,43],"tags":[],"class_list":["post-1148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tractor","category-historia","penguin-post","penguin-post-not-sticky"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Case IH, historia de una marca - BLOG<\/title>\n<meta name=\"description\" content=\"La historia de la marca Case Ih comienza en el a\u00f1o 1985 tras muchos a\u00f1os de trabajo y \u00e9xito por parte de diferentes compa\u00f1\u00edas de maquinaria agr\u00edcola.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Case IH, historia de una marca - BLOG\" \/>\n<meta property=\"og:description\" content=\"La historia de la marca Case Ih comienza en el a\u00f1o 1985 tras muchos a\u00f1os de trabajo y \u00e9xito por parte de diferentes compa\u00f1\u00edas de maquinaria agr\u00edcola.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-15T13:16:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-15T09:15:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FUSTER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FUSTER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/\"},\"author\":{\"name\":\"FUSTER\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\"},\"headline\":\"Case IH, historia de una marca\",\"datePublished\":\"2020-01-15T13:16:39+00:00\",\"dateModified\":\"2020-05-15T09:15:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/\"},\"wordCount\":612,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH.jpg\",\"articleSection\":[\"El tractor\",\"Historia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/\",\"name\":\"Case IH, historia de una marca - BLOG\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH.jpg\",\"datePublished\":\"2020-01-15T13:16:39+00:00\",\"dateModified\":\"2020-05-15T09:15:51+00:00\",\"description\":\"La historia de la marca Case Ih comienza en el a\u00f1o 1985 tras muchos a\u00f1os de trabajo y \u00e9xito por parte de diferentes compa\u00f1\u00edas de maquinaria agr\u00edcola.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#primaryimage\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH.jpg\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH.jpg\",\"width\":1920,\"height\":460,\"caption\":\"Case IH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.repuestosfuster.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case IH, historia de una marca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"name\":\"Repuestos Fuster Blog\",\"description\":\"Tu blog de agricultura y tractores\",\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\",\"name\":\"Repuestos Fuster\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"width\":300,\"height\":120,\"caption\":\"Repuestos Fuster\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\",\"name\":\"FUSTER\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"caption\":\"FUSTER\"},\"description\":\"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.\",\"sameAs\":[\"http:\/\/www.repuestosfuster.com\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Case IH, historia de una marca - BLOG","description":"La historia de la marca Case Ih comienza en el a\u00f1o 1985 tras muchos a\u00f1os de trabajo y \u00e9xito por parte de diferentes compa\u00f1\u00edas de maquinaria agr\u00edcola.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/","og_locale":"es_ES","og_type":"article","og_title":"Case IH, historia de una marca - BLOG","og_description":"La historia de la marca Case Ih comienza en el a\u00f1o 1985 tras muchos a\u00f1os de trabajo y \u00e9xito por parte de diferentes compa\u00f1\u00edas de maquinaria agr\u00edcola.","og_url":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/","og_site_name":"BLOG","article_published_time":"2020-01-15T13:16:39+00:00","article_modified_time":"2020-05-15T09:15:51+00:00","og_image":[{"width":1920,"height":460,"url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH.jpg","type":"image\/jpeg"}],"author":"FUSTER","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"FUSTER","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#article","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/"},"author":{"name":"FUSTER","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3"},"headline":"Case IH, historia de una marca","datePublished":"2020-01-15T13:16:39+00:00","dateModified":"2020-05-15T09:15:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/"},"wordCount":612,"commentCount":0,"publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH.jpg","articleSection":["El tractor","Historia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/","url":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/","name":"Case IH, historia de una marca - BLOG","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#primaryimage"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH.jpg","datePublished":"2020-01-15T13:16:39+00:00","dateModified":"2020-05-15T09:15:51+00:00","description":"La historia de la marca Case Ih comienza en el a\u00f1o 1985 tras muchos a\u00f1os de trabajo y \u00e9xito por parte de diferentes compa\u00f1\u00edas de maquinaria agr\u00edcola.","breadcrumb":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#primaryimage","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH.jpg","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH.jpg","width":1920,"height":460,"caption":"Case IH"},{"@type":"BreadcrumbList","@id":"https:\/\/www.repuestosfuster.com\/blog\/case-ih-la-historia-una-marca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repuestosfuster.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Case IH, historia de una marca"}]},{"@type":"WebSite","@id":"https:\/\/www.repuestosfuster.com\/blog\/#website","url":"https:\/\/www.repuestosfuster.com\/blog\/","name":"Repuestos Fuster Blog","description":"Tu blog de agricultura y tractores","publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization","name":"Repuestos Fuster","url":"https:\/\/www.repuestosfuster.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","width":300,"height":120,"caption":"Repuestos Fuster"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3","name":"FUSTER","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","caption":"FUSTER"},"description":"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.","sameAs":["http:\/\/www.repuestosfuster.com\/"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2020\/01\/Case_IH.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8NulZ-iw","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/1148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/comments?post=1148"}],"version-history":[{"count":0,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/1148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media\/1150"}],"wp:attachment":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media?parent=1148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/categories?post=1148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/tags?post=1148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}