{"id":1114,"date":"2019-12-05T11:31:36","date_gmt":"2019-12-05T11:31:36","guid":{"rendered":"http:\/\/www.repuestosfuster.com\/blog\/?p=1114"},"modified":"2020-05-15T09:15:59","modified_gmt":"2020-05-15T09:15:59","slug":"ebro-marca-con-denominacion-de-origen","status":"publish","type":"post","link":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/","title":{"rendered":"Ebro, una marca con denominaci\u00f3n de origen"},"content":{"rendered":"<p style=\"text-align: justify;\">Los or\u00edgenes de los tractores <strong>Ebro<\/strong> se remontan a 1952, cuando el Ministerio de Industria de Espa\u00f1a convoca un concurso p\u00fablico destinado a potenciar la deficiente industria nacional del tractor. El ganador de dicha convocatoria es Ford, cuya divisi\u00f3n Ford Motor Ib\u00e9rica estaba asentada en Espa\u00f1a desde la d\u00e9cada de 1920. Dos a\u00f1os despu\u00e9s, las desavenencias entre la popular compa\u00f1\u00eda y el r\u00e9gimen hacen que Ford venda sus acciones espa\u00f1olas dando lugar a una nueva compa\u00f1\u00eda destinada a sentar historia en el campo de la fabricaci\u00f3n de tractores en Espa\u00f1a: <strong>Motor Ib\u00e9rica S.A.<\/strong><\/p>\n<h3><strong>Unos inicios prometedores<\/strong><\/h3>\n<p style=\"text-align: justify;\">Desde sus inicios, esta nueva empresa cuenta con el apoyo t\u00e9cnico de Ford Motor Company, y este hecho se deja ver en los primeros productos de la nueva marca espa\u00f1ola. As\u00ed, en 1955 ve la luz el primer tractor de la compa\u00f1\u00eda, el <strong>Ebro 38<\/strong>, un veh\u00edculo de 38 cv de potencia que supuso todo un hito para la industria automovil\u00edstica nacional, y m\u00e1s teniendo en cuenta las deficiencias t\u00e9cnicas y productivas de la Espa\u00f1a de los a\u00f1os 50. La producci\u00f3n del Ebro 38 se mantiene estable y pr\u00e1cticamente inmutable hasta 1961, a\u00f1o en el que el nuevo modelo <strong>S\u00faper Ebro<\/strong> confirma las altas expectativas puestas la labor de Motor Ib\u00e9rica como fabricante de tractores.<\/p>\n<h3><strong>Nuevos socios, nuevos productos Ebro<\/strong><\/h3>\n<p style=\"text-align: justify;\">En el a\u00f1o 1965, <strong><span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/www.repuestosfuster.com\/es\/productos\/massey-ferguson\" target=\"_blank\" rel=\"noopener noreferrer\">Massey Ferguson<\/a><\/span><\/strong> compra a <strong><span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/www.repuestosfuster.com\/es\/productos\/ford\" target=\"_blank\" rel=\"noopener noreferrer\">Ford<\/a> <\/span><\/strong>el 40 % de las acciones de Motor Ib\u00e9rica. Comienza entonces una nueva y fruct\u00edfera alianza que tiene como primer resultado la aparici\u00f3n del <strong>Ebro 160<\/strong> en el a\u00f1o 1967. Por estos a\u00f1os, la sede de la empresa se traslada a Barcelona y la l\u00ednea de producci\u00f3n se ampl\u00eda con la fabricaci\u00f3n de furgonetas, carretillas elevadoras e incluso veh\u00edculos todoterreno. El crecimiento tanto cualitativo como cuantitativo de la compa\u00f1\u00eda afianza su posicionamiento como una de las empresas m\u00e1s potentes del pa\u00eds. En 1973, Motor Ib\u00e9rica adquiere la compa\u00f1\u00eda de maquinaria y repuestos agr\u00edcolas Valpadana.<\/p>\n<p><\/br><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1118\" data-permalink=\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/logo_ebro-2\/\" data-orig-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/logo_Ebro-1.jpg\" data-orig-size=\"1231,872\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"logo_Ebro\" data-image-description=\"&lt;p&gt;logo_Ebro&lt;\/p&gt;\n\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/logo_Ebro-1-300x213.jpg\" data-large-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/logo_Ebro-1-1024x725.jpg\" class=\" wp-image-1118 aligncenter\" src=\"http:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/logo_Ebro-1.jpg\" alt=\"logo_Ebro\" width=\"554\" height=\"392\" srcset=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/logo_Ebro-1.jpg 1231w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/logo_Ebro-1-300x213.jpg 300w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/logo_Ebro-1-768x544.jpg 768w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/logo_Ebro-1-1024x725.jpg 1024w\" sizes=\"auto, (max-width: 599px) calc(100vw - 50px), (max-width: 767px) calc(100vw - 70px), (max-width: 991px) 429px, (max-width: 1199px) 637px, 354px\" \/><\/p>\n<p style=\"text-align: justify;\">La entrada en la d\u00e9cada de 1980 supone tambi\u00e9n el nacimiento de la edad de oro del tractor en Espa\u00f1a debido a la salida al mercado de la serie <strong>Ebro 6000<\/strong>. Con este nuevo modelo, Motor Ib\u00e9rica vuelve a tocar el cielo de la producci\u00f3n de maquinaria agr\u00edcola. Por estos a\u00f1os, Massey Ferguson vende su participaci\u00f3n en la empresa a los japoneses <strong>Nissan<\/strong> que, tras varias operaciones, terminan ali\u00e1ndose con <a href=\"https:\/\/es.wikipedia.org\/wiki\/Kubota\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><span style=\"color: #ff9900;\">Kubota<\/span><\/strong><\/a> para generar una nueva marca de tractores en 1986: <strong>Ebro &#8211; Kubota<\/strong>.<\/p>\n<h3><strong>La aventura japonesa<\/strong><\/h3>\n<p style=\"text-align: justify;\">La sede de la empresa se traslada a Madrid y comienza a formarse una nueva plantilla de profesionales que se ve reforzada por la llegada de ingenieros japoneses empleados por <span style=\"color: #ff9900;\"><strong><a style=\"color: #ff9900;\" href=\"https:\/\/www.repuestosfuster.com\/es\/productos\/ebro-kubota\" target=\"_blank\" rel=\"noopener noreferrer\">Kubota<\/a><\/strong><\/span>. Progresivamente, la marca nipona comienza a adquirir un mayor peso en la compa\u00f1\u00eda hasta lograr hacerse con la mayor\u00eda de las acciones. La productividad de Motor Ib\u00e9rica crece hasta las 8000 unidades anuales y, como resultado de todas estas mejoras t\u00e9cnicas, sale a la luz la nueva <strong>serie 8000<\/strong>, que se constituye como un nuevo hito de la industria del tractor en Espa\u00f1a.<\/p>\n<p style=\"text-align: justify;\">Pese a todos los logros, en 1994 la compa\u00f1\u00eda arrastra unas p\u00e9rdidas operativas de 12 millones de pesetas. Los directivos de Kubota realizan un viaje a Jap\u00f3n para solicitar una ampliaci\u00f3n de capital, pero en su lugar reciben otra noticia: Ebro &#8211; Kubota cierra sus puertas. El cierre de la compa\u00f1\u00eda coincide con el proceso de fabricaci\u00f3n de un nuevo modelo, el <strong>K1<\/strong>, que saldr\u00e1 al mercado con la marca Kubota.<\/p>\n<p style=\"text-align: justify;\">En opini\u00f3n de muchos, el fin de la compa\u00f1\u00eda respondi\u00f3 a una decisi\u00f3n precipitada realizada desde una distancia que, tal vez, impidi\u00f3 valorar con sensatez las posibilidades de recuperaci\u00f3n y crecimiento. Parece ser que la c\u00fapula japonesa decidi\u00f3 finalizar la historia de Ebro-Kubota al ver que el mercado europeo no era tan f\u00e1cil de conquistar como pensaban.<\/p>\n<p style=\"text-align: justify;\">Imagen principal de <a href=\"https:\/\/www.flickr.com\/photos\/26524778@N02\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><span style=\"color: #ff9900;\">P. Le\u00f3n<\/span><\/strong><\/a><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;1114&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5\\\/5 - (1 voto)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Ebro, una marca con denominaci\u00f3n de origen&quot;,&quot;width&quot;:&quot;142.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 142.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            5\/5 - (1 voto)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ebro es sin lugar a dudas la marca m\u00e1s famosa de tractores espa\u00f1oles. Sus veh\u00edculos azules son ya parte de la memoria colectiva de la agricultura nacional.<\/p>\n<a href=\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/\" class=\"read-more-link\">Continua leyendo <span class=\"screen-reader-text\">\"Ebro, una marca con denominaci\u00f3n de origen\"<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a>","protected":false},"author":1,"featured_media":1115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[43,1],"tags":[],"class_list":["post-1114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia","category-noticias","penguin-post","penguin-post-not-sticky"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ebro, una marca con denominaci\u00f3n de origen - BLOG<\/title>\n<meta name=\"description\" content=\"Ebro es sin lugar a dudas la marca m\u00e1s famosa de tractores espa\u00f1oles. Sus veh\u00edculos azules son ya parte de la memoria colectiva de la agricultura nacional.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ebro, una marca con denominaci\u00f3n de origen - BLOG\" \/>\n<meta property=\"og:description\" content=\"Ebro es sin lugar a dudas la marca m\u00e1s famosa de tractores espa\u00f1oles. Sus veh\u00edculos azules son ya parte de la memoria colectiva de la agricultura nacional.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-05T11:31:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-15T09:15:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/ebro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FUSTER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FUSTER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/\"},\"author\":{\"name\":\"FUSTER\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\"},\"headline\":\"Ebro, una marca con denominaci\u00f3n de origen\",\"datePublished\":\"2019-12-05T11:31:36+00:00\",\"dateModified\":\"2020-05-15T09:15:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/\"},\"wordCount\":694,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/ebro.jpg\",\"articleSection\":[\"Historia\",\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/\",\"name\":\"Ebro, una marca con denominaci\u00f3n de origen - BLOG\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/ebro.jpg\",\"datePublished\":\"2019-12-05T11:31:36+00:00\",\"dateModified\":\"2020-05-15T09:15:59+00:00\",\"description\":\"Ebro es sin lugar a dudas la marca m\u00e1s famosa de tractores espa\u00f1oles. Sus veh\u00edculos azules son ya parte de la memoria colectiva de la agricultura nacional.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#primaryimage\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/ebro.jpg\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/ebro.jpg\",\"width\":1920,\"height\":460,\"caption\":\"Ebro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.repuestosfuster.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ebro, una marca con denominaci\u00f3n de origen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"name\":\"Repuestos Fuster Blog\",\"description\":\"Tu blog de agricultura y tractores\",\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\",\"name\":\"Repuestos Fuster\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"width\":300,\"height\":120,\"caption\":\"Repuestos Fuster\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\",\"name\":\"FUSTER\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"caption\":\"FUSTER\"},\"description\":\"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.\",\"sameAs\":[\"http:\/\/www.repuestosfuster.com\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ebro, una marca con denominaci\u00f3n de origen - BLOG","description":"Ebro es sin lugar a dudas la marca m\u00e1s famosa de tractores espa\u00f1oles. Sus veh\u00edculos azules son ya parte de la memoria colectiva de la agricultura nacional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/","og_locale":"es_ES","og_type":"article","og_title":"Ebro, una marca con denominaci\u00f3n de origen - BLOG","og_description":"Ebro es sin lugar a dudas la marca m\u00e1s famosa de tractores espa\u00f1oles. Sus veh\u00edculos azules son ya parte de la memoria colectiva de la agricultura nacional.","og_url":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/","og_site_name":"BLOG","article_published_time":"2019-12-05T11:31:36+00:00","article_modified_time":"2020-05-15T09:15:59+00:00","og_image":[{"width":1920,"height":460,"url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/ebro.jpg","type":"image\/jpeg"}],"author":"FUSTER","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"FUSTER","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#article","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/"},"author":{"name":"FUSTER","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3"},"headline":"Ebro, una marca con denominaci\u00f3n de origen","datePublished":"2019-12-05T11:31:36+00:00","dateModified":"2020-05-15T09:15:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/"},"wordCount":694,"commentCount":0,"publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/ebro.jpg","articleSection":["Historia","Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/","url":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/","name":"Ebro, una marca con denominaci\u00f3n de origen - BLOG","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#primaryimage"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/ebro.jpg","datePublished":"2019-12-05T11:31:36+00:00","dateModified":"2020-05-15T09:15:59+00:00","description":"Ebro es sin lugar a dudas la marca m\u00e1s famosa de tractores espa\u00f1oles. Sus veh\u00edculos azules son ya parte de la memoria colectiva de la agricultura nacional.","breadcrumb":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#primaryimage","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/ebro.jpg","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/ebro.jpg","width":1920,"height":460,"caption":"Ebro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.repuestosfuster.com\/blog\/ebro-marca-con-denominacion-de-origen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repuestosfuster.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Ebro, una marca con denominaci\u00f3n de origen"}]},{"@type":"WebSite","@id":"https:\/\/www.repuestosfuster.com\/blog\/#website","url":"https:\/\/www.repuestosfuster.com\/blog\/","name":"Repuestos Fuster Blog","description":"Tu blog de agricultura y tractores","publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization","name":"Repuestos Fuster","url":"https:\/\/www.repuestosfuster.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","width":300,"height":120,"caption":"Repuestos Fuster"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3","name":"FUSTER","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","caption":"FUSTER"},"description":"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.","sameAs":["http:\/\/www.repuestosfuster.com\/"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/12\/ebro.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8NulZ-hY","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/1114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/comments?post=1114"}],"version-history":[{"count":0,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/1114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media\/1115"}],"wp:attachment":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media?parent=1114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/categories?post=1114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/tags?post=1114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}