{"id":1065,"date":"2019-10-30T10:46:44","date_gmt":"2019-10-30T10:46:44","guid":{"rendered":"http:\/\/www.repuestosfuster.com\/blog\/?p=1065"},"modified":"2019-11-04T10:54:29","modified_gmt":"2019-11-04T10:54:29","slug":"hidroponia-cultivo-de-plantas-sin-suelo","status":"publish","type":"post","link":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/","title":{"rendered":"Hidropon\u00eda, o el cultivo de plantas sin suelo"},"content":{"rendered":"<p style=\"text-align: justify;\">Por norma general, las plantas encuentran en el suelo su principal fuente de nutrientes y el medio alrededor del cual se desarrollan y viven. Sin embargo, la tierra no siempre resulta indispensable para garantizar la vida de los vegetales ya que esta es susceptible de ser sustituida por otros medios como, por ejemplo, el agua. Esta es la base de la <strong>hidropon\u00eda<\/strong>, un popular m\u00e9todo de cultivo que utiliza disoluciones minerales en lugar de suelo agr\u00edcola.<\/p>\n<h3><strong>\u00bfDe d\u00f3nde viene la hidropon\u00eda?<\/strong><\/h3>\n<p style=\"text-align: justify;\">Pese a que no haya una evidencia clara sobre en qu\u00e9 momento comenz\u00f3 a utilizarse este m\u00e9todo, se cree que su aplicaci\u00f3n fue bastante temprana. A este respecto, existen teor\u00edas que sit\u00faan ya su presencia en la antigua <strong>Babilonia<\/strong>, m\u00e1s concretamente en los <strong><span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/es.wikipedia.org\/wiki\/Jardines_Colgantes_de_Babilonia\" target=\"_blank\" rel=\"noopener noreferrer\">jardines colgantes<\/a><\/span><\/strong> del rey Nabucodonosor II. Otras culturas como la azteca o la romana tambi\u00e9n cultivaron vegetales mediante t\u00e9cnicas que podr\u00edan considerarse antecedentes directas de la hidropon\u00eda. Sea como sea, para hablar de esta modalidad en un sentido estricto hay que remontarse a una \u00e9poca bastante m\u00e1s cercana, concretamente a 1600, cuando aparece la primera referencia escrita al respecto por parte del belga <strong>Jan Van Helmot<\/strong>. A\u00f1os despu\u00e9s, en 1927, <strong>Francis Bacon<\/strong> contribuye al asentamiento de la hidropon\u00eda mediante la publicaci\u00f3n de su estudio <em>Sylva sylvarum<\/em>, sobre el desarrollo de plantas terrestres en ausencia de suelo. El empuje definitivo tiene lugar durante el siglo XIX, cuando se desarrollan definitivamente las soluciones de nutrientes disueltas en agua que son la base de la hidropon\u00eda contempor\u00e1nea.<\/p>\n<h3><strong>La hidropon\u00eda en la actualidad<\/strong><\/h3>\n<p style=\"text-align: justify;\">De esta manera, en la actualidad la hidropon\u00eda contin\u00faa teniendo su principal axioma en el empleo de <strong>disoluciones minerales<\/strong> en lugar de suelo. Las plantas pueden colocarse en soportes o contenedores de diferente forma y tama\u00f1o siempre que estos permitan que las ra\u00edces se encuentren en suspensi\u00f3n. Una vez posicionada la planta, la ra\u00edz es sumergida en una soluci\u00f3n acuosa que contiene los <strong>nutrientes minerales<\/strong> disueltos. Por norma general, esta soluci\u00f3n mineral busca un equilibrio entre los 13 elementos minerales que mejores resultados tienen sobre la vida vegetal y que son el nitr\u00f3geno, el f\u00f3sforo, el potasio, el azufre, el f\u00f3sforo, el calcio, el hierro, el magnesio, el zinc, el boro, el cobre, el silicio y el molibdeno.<\/p>\n<p><\/br><br \/>\n<div id=\"attachment_1068\" style=\"width: 545px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1068\" data-attachment-id=\"1068\" data-permalink=\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/hidro_3\/\" data-orig-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_3.jpg\" data-orig-size=\"1920,1440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Hidropon\u00eda_2\" data-image-description=\"&lt;p&gt;Hidropon\u00eda_2&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Cultivo hidrop\u00f3nico&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_3-300x225.jpg\" data-large-file=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_3-1024x768.jpg\" class=\" wp-image-1068\" src=\"http:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_3.jpg\" alt=\"Hidropon\u00eda_2\" width=\"535\" height=\"401\" srcset=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_3.jpg 1920w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_3-300x225.jpg 300w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_3-768x576.jpg 768w, https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_3-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 599px) calc(100vw - 50px), (max-width: 767px) calc(100vw - 70px), (max-width: 991px) 429px, (max-width: 1199px) 637px, 354px\" \/><p id=\"caption-attachment-1068\" class=\"wp-caption-text\">Cultivo hidrop\u00f3nico<\/p><\/div><\/p>\n<p style=\"text-align: justify;\">Desde hace unas d\u00e9cadas, la hidropon\u00eda est\u00e1 conociendo un f\u00e9rtil periodo de desarrollo, investigaci\u00f3n y fama. La alineaci\u00f3n con otra clase de m\u00e9todos productivos que descartan el empleo de pesticidas y productos qu\u00edmicos puede ser una de los principales motivos de su popularidad. Su presencia es m\u00e1s notable en el \u00e1mbito dom\u00e9stico, en espacios urbanos y en peque\u00f1os cultivos, pero paulatinamente comienzan a desarrollarse proyectos de mayor calado que cuentan con ella como medio de trabajo. Algunos buenos ejemplos de ello son el huerto ant\u00e1rtico Eden ISS de la <strong><span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"http:\/\/www.repuestosfuster.com\/blog\/vegetales-en-la-antartida\/\" target=\"_blank\" rel=\"noopener noreferrer\">base polar Neumayer III<\/a><\/span><\/strong> o la <strong><span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"http:\/\/www.repuestosfuster.com\/blog\/que-es-la-acuoponia\/\" target=\"_blank\" rel=\"noopener noreferrer\">acuopon\u00eda<\/a><\/span><\/strong>, una t\u00e9cnica que a\u00fana el cultivo de plantas sin suelo con la cr\u00eda de peces.<\/p>\n<h3 style=\"text-align: justify;\"><strong>A favor y en contra<\/strong><\/h3>\n<p style=\"text-align: justify;\">Como sucede con toda t\u00e9cnica de car\u00e1cter novedoso, a la hidropon\u00eda se le han dedicado muchos elogios y algunas menos cr\u00edticas. En general, las <strong>ventajas<\/strong> que esta t\u00e9cnica lleva asociadas son las siguientes.<\/p>\n<ul>\n<li>\n<p style=\"text-align: justify;\">Eliminaci\u00f3n del uso de <strong>pesticidas<\/strong> y agentes qu\u00edmicos.<\/p>\n<\/li>\n<li>\n<p style=\"text-align: justify;\">Se <strong>reduce el espacio de cultivo<\/strong> ya que la ra\u00edz no necesita crecer para alcanzar el alimento.<\/p>\n<\/li>\n<li>\n<p style=\"text-align: justify;\">El agua empleada para disolver los nutrientes puede ser <strong>reutilizada<\/strong>, lo que supone un notable ahorro.<\/p>\n<\/li>\n<li>\n<p style=\"text-align: justify;\">Existe una alta capacidad para <strong>personalizar<\/strong> el n\u00famero y la intensidad de los diferentes nutrientes empleados para su disoluci\u00f3n.<\/p>\n<\/li>\n<li>\n<p style=\"text-align: justify;\">Permite el cultivo en estructuras alternativas como, por ejemplo, verticales. Este hecho supone un importante <strong>ahorro espacial<\/strong>.<\/p>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">En la otra cara de la moneda, la hidropon\u00eda tiene tambi\u00e9n varios <strong>puntos en su contra<\/strong>. Los principales derivan del elevado coste energ\u00e9tico que pueden suponer los sistemas de riego empleados, pero tambi\u00e9n se habla de la necesidad de llevar a cabo un mayor control del riego, m\u00e1s constante y ajustado a las demandas de las plantas.<\/p>\n<p style=\"text-align: justify;\">Sea como sea, la hidropon\u00eda es una t\u00e9cnica que puede suponer interesantes avances en el cultivo de plantas, especialmente en terrenos de peque\u00f1as dimensiones o espacios alternativos como el dom\u00e9stico o el urbano.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;1065&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5\\\/5 - (1 voto)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Hidropon\u00eda, o el cultivo de plantas sin suelo&quot;,&quot;width&quot;:&quot;142.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 142.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            5\/5 - (1 voto)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>La hidropon\u00eda es una t\u00e9cnica de cultivo que cambia el suelo por una mezcla de nutrientes disueltos en agua. Como todo, tiene sus seguidores y detractores.<\/p>\n<a href=\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/\" class=\"read-more-link\">Continua leyendo <span class=\"screen-reader-text\">\"Hidropon\u00eda, o el cultivo de plantas sin suelo\"<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a>","protected":false},"author":1,"featured_media":1066,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[36],"tags":[],"class_list":["post-1065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-sector","penguin-post","penguin-post-not-sticky"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hidropon\u00eda, o el cultivo de plantas sin suelo - BLOG<\/title>\n<meta name=\"description\" content=\"La hidropon\u00eda es una t\u00e9cnica de cultivo que cambia el suelo por una mezcla de nutrientes disueltos en agua. Como todo, tiene sus seguidores y detractores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hidropon\u00eda, o el cultivo de plantas sin suelo - BLOG\" \/>\n<meta property=\"og:description\" content=\"La hidropon\u00eda es una t\u00e9cnica de cultivo que cambia el suelo por una mezcla de nutrientes disueltos en agua. Como todo, tiene sus seguidores y detractores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-30T10:46:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-04T10:54:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_1_rec.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FUSTER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FUSTER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/\"},\"author\":{\"name\":\"FUSTER\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\"},\"headline\":\"Hidropon\u00eda, o el cultivo de plantas sin suelo\",\"datePublished\":\"2019-10-30T10:46:44+00:00\",\"dateModified\":\"2019-11-04T10:54:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/\"},\"wordCount\":770,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_1_rec.jpg\",\"articleSection\":[\"El sector\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/\",\"name\":\"Hidropon\u00eda, o el cultivo de plantas sin suelo - BLOG\",\"isPartOf\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_1_rec.jpg\",\"datePublished\":\"2019-10-30T10:46:44+00:00\",\"dateModified\":\"2019-11-04T10:54:29+00:00\",\"description\":\"La hidropon\u00eda es una t\u00e9cnica de cultivo que cambia el suelo por una mezcla de nutrientes disueltos en agua. Como todo, tiene sus seguidores y detractores.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#primaryimage\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_1_rec.jpg\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_1_rec.jpg\",\"width\":1920,\"height\":460,\"caption\":\"hidropon\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.repuestosfuster.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hidropon\u00eda, o el cultivo de plantas sin suelo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#website\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"name\":\"Repuestos Fuster Blog\",\"description\":\"Tu blog de agricultura y tractores\",\"publisher\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#organization\",\"name\":\"Repuestos Fuster\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"contentUrl\":\"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png\",\"width\":300,\"height\":120,\"caption\":\"Repuestos Fuster\"},\"image\":{\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3\",\"name\":\"FUSTER\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g\",\"caption\":\"FUSTER\"},\"description\":\"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.\",\"sameAs\":[\"http:\/\/www.repuestosfuster.com\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hidropon\u00eda, o el cultivo de plantas sin suelo - BLOG","description":"La hidropon\u00eda es una t\u00e9cnica de cultivo que cambia el suelo por una mezcla de nutrientes disueltos en agua. Como todo, tiene sus seguidores y detractores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/","og_locale":"es_ES","og_type":"article","og_title":"Hidropon\u00eda, o el cultivo de plantas sin suelo - BLOG","og_description":"La hidropon\u00eda es una t\u00e9cnica de cultivo que cambia el suelo por una mezcla de nutrientes disueltos en agua. Como todo, tiene sus seguidores y detractores.","og_url":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/","og_site_name":"BLOG","article_published_time":"2019-10-30T10:46:44+00:00","article_modified_time":"2019-11-04T10:54:29+00:00","og_image":[{"width":1920,"height":460,"url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_1_rec.jpg","type":"image\/jpeg"}],"author":"FUSTER","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"FUSTER","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#article","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/"},"author":{"name":"FUSTER","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3"},"headline":"Hidropon\u00eda, o el cultivo de plantas sin suelo","datePublished":"2019-10-30T10:46:44+00:00","dateModified":"2019-11-04T10:54:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/"},"wordCount":770,"commentCount":0,"publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_1_rec.jpg","articleSection":["El sector"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/","url":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/","name":"Hidropon\u00eda, o el cultivo de plantas sin suelo - BLOG","isPartOf":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#primaryimage"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_1_rec.jpg","datePublished":"2019-10-30T10:46:44+00:00","dateModified":"2019-11-04T10:54:29+00:00","description":"La hidropon\u00eda es una t\u00e9cnica de cultivo que cambia el suelo por una mezcla de nutrientes disueltos en agua. Como todo, tiene sus seguidores y detractores.","breadcrumb":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#primaryimage","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_1_rec.jpg","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_1_rec.jpg","width":1920,"height":460,"caption":"hidropon\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.repuestosfuster.com\/blog\/hidroponia-cultivo-de-plantas-sin-suelo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repuestosfuster.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Hidropon\u00eda, o el cultivo de plantas sin suelo"}]},{"@type":"WebSite","@id":"https:\/\/www.repuestosfuster.com\/blog\/#website","url":"https:\/\/www.repuestosfuster.com\/blog\/","name":"Repuestos Fuster Blog","description":"Tu blog de agricultura y tractores","publisher":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repuestosfuster.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.repuestosfuster.com\/blog\/#organization","name":"Repuestos Fuster","url":"https:\/\/www.repuestosfuster.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","contentUrl":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2017\/03\/logo-fuster.png","width":300,"height":120,"caption":"Repuestos Fuster"},"image":{"@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repuestosfuster.com\/blog\/#\/schema\/person\/96301f462c55228d9d330690c83db2b3","name":"FUSTER","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00201df07a21b34b695826e786430d6bd01ef7530dd6745786b4e32666a277e4?s=96&d=mm&r=g","caption":"FUSTER"},"description":"Repuestos Fuster es un fabricante de recambios para tractores cuyo principal objetivo es la producci\u00f3n rigurosa y garantizada de repuestos con la misma calidad que la pieza original a un precio m\u00e1s econ\u00f3mico.","sameAs":["http:\/\/www.repuestosfuster.com\/"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.repuestosfuster.com\/blog\/wp-content\/uploads\/2019\/11\/hidro_1_rec.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8NulZ-hb","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/1065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/comments?post=1065"}],"version-history":[{"count":0,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/posts\/1065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media\/1066"}],"wp:attachment":[{"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/media?parent=1065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/categories?post=1065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repuestosfuster.com\/blog\/wp-json\/wp\/v2\/tags?post=1065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}